{"id":5881,"date":"2025-12-03T19:31:38","date_gmt":"2025-12-03T19:31:38","guid":{"rendered":"https:\/\/komanlakeferry.com\/fuinn\/"},"modified":"2026-05-12T12:24:11","modified_gmt":"2026-05-12T12:24:11","slug":"fuinn","status":"publish","type":"page","link":"https:\/\/komanlakeferry.com\/ga\/fuinn\/","title":{"rendered":"F\u00daINN"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"5881\" class=\"elementor elementor-5881 elementor-28\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-170da54 e-con-full e-flex e-con e-parent\" data-id=\"170da54\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-e2a9ce8 e-con-full e-flex e-con e-child\" data-id=\"e2a9ce8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-21184cf elementor-widget elementor-widget-spacer\" data-id=\"21184cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-961f13a elementor-widget elementor-widget-spacer\" data-id=\"961f13a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-13860e3 e-flex e-con-boxed e-con e-parent\" data-id=\"13860e3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-2c9b177 e-con-full e-flex e-con e-child\" data-id=\"2c9b177\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ebf66eb elementor-widget elementor-widget-heading\" data-id=\"ebf66eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">About us<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fa56baf elementor-widget elementor-widget-shortcode\" data-id=\"fa56baf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><nav aria-label=\"breadcrumbs\" class=\"rank-math-breadcrumb\"><p><span class=\"last\">Home<\/span><\/p><\/nav><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a1a5f77 e-con-full e-flex e-con e-parent\" data-id=\"a1a5f77\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-e75d81c e-con-full e-flex e-con e-child\" data-id=\"e75d81c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1f63cf5 elementor-cta--skin-classic elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"1f63cf5\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"sec1\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/komanlakeferry.com\/wp-content\/uploads\/2026\/01\/nord-west-cruise.webp);\" role=\"img\" aria-label=\"Nord West Ferry\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-18c7d6e elementor-cta--skin-classic elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"18c7d6e\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"sec2\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/komanlakeferry.com\/wp-content\/uploads\/2026\/01\/Koman-to-Fierz-Ferry-Boat-Trip.webp);\" role=\"img\" aria-label=\"Trasn\u00fa c\u00e1ili\u00fail b\u00e1id farant\u00f3ireachta \u00f3 Koman go Fierz ar Loch Koman\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ad382b elementor-cta--skin-classic elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"9ad382b\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"sec3\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/komanlakeferry.com\/wp-content\/uploads\/2026\/01\/IMG_4161.jpg);\" role=\"img\" aria-label=\"Komani Lake cruise\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-096dea9 e-con-full e-flex e-con e-child\" data-id=\"096dea9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-959be10 e-con-full e-flex e-con e-child\" data-id=\"959be10\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_offset&quot;:100,&quot;sticky_parent&quot;:&quot;yes&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5b21b6e elementor-widget-divider--view-line_text elementor-widget-divider--element-align-center elementor-invisible elementor-widget elementor-widget-divider\" data-id=\"5b21b6e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<span class=\"elementor-divider__text elementor-divider__element\">\n\t\t\t\tNORDWEST\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3cf1853 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"3cf1853\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Taisc\u00e9al Tuaisceart na hAlb\u00e1ine<br \/>le NordWest<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9f07a31 elementor-absolute elementor-widget elementor-widget-html\" data-id=\"9f07a31\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"html.default\">\n\t\t\t\t\t<div class=\"timeline-dot\" id=\"dot1\">\r\n  <svg width=\"50\" height=\"50\" viewbox=\"-10 -50 100 150\">\r\n    <circle cx=\"40\" cy=\"40\" r=\"46\" fill=\"white\"><\/circle>\r\n    <circle cx=\"40\" cy=\"40\" r=\"33\" fill=\"#FA7C00\"><\/circle>\r\n<circle cx=\"40\" cy=\"40\" r=\"30\" fill=\"white\" class=\"dot-core\"><\/circle>\r\n\r\n  <\/svg>\r\n<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-478fb19 elementor-absolute elementor-widget elementor-widget-html\" data-id=\"478fb19\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"html.default\">\n\t\t\t\t\t<div class=\"timeline-dot\" id=\"dot2\">\r\n  <svg width=\"50\" height=\"50\" viewbox=\"-10 -50 100 150\">\r\n    <circle cx=\"40\" cy=\"40\" r=\"46\" fill=\"white\"><\/circle>\r\n    <circle cx=\"40\" cy=\"40\" r=\"33\" fill=\"#FA7C00\"><\/circle>\r\n<circle cx=\"40\" cy=\"40\" r=\"30\" fill=\"white\" class=\"dot-core\"><\/circle>\r\n\r\n  <\/svg>\r\n<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3940b80 elementor-absolute elementor-widget elementor-widget-html\" data-id=\"3940b80\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"html.default\">\n\t\t\t\t\t<div class=\"timeline-dot\" id=\"dot3\">\r\n  <svg width=\"50\" height=\"50\" viewbox=\"-10 -50 100 150\">\r\n    <circle cx=\"40\" cy=\"40\" r=\"46\" fill=\"white\"><\/circle>\r\n    <circle cx=\"40\" cy=\"40\" r=\"33\" fill=\"#FA7C00\"><\/circle>\r\n<circle cx=\"40\" cy=\"40\" r=\"30\" fill=\"white\" class=\"dot-core\"><\/circle>\r\n\r\n  <\/svg>\r\n<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-207b86b elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"207b86b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Is oibreoir turas gairmi\u00fail agus l\u00e1nchead\u00fanaithe \u00e9 Nord West Ferry at\u00e1 speisialaithe i dturais bh\u00e1id paisin\u00e9ir\u00ed pr\u00e9imhe agus i dtaith\u00ed taistil chomhcheangailte trasna Loch Komani \u2014 ceann de na cinn scr\u00edbe is radharcach agus is gan mhilleadh san Alb\u00e1in agus i r\u00e9igi\u00fan na mBalc\u00e1n. <br>Is \u00e9 \u00e1r misean turais sh\u00e1bh\u00e1ilte, chompordacha agus dea-eagraithe a shol\u00e1thar tr\u00ed th\u00edrdhreacha dr\u00e1mat\u00fala thuaisceart na hAlb\u00e1ine, ag comhcheangal loingseoireacht radharcach, seirbh\u00eds ghairmi\u00fail agus l\u00f3ist\u00edocht iontaofa. <br>Le b\u00e9im l\u00e1idir ar ch\u00e1il\u00edocht, s\u00e1bh\u00e1ilteacht agus taith\u00ed paisin\u00e9ir\u00ed, t\u00e1 Nord West Ferry ina rogha iontaofa do thaistealaithe at\u00e1 ag lorg turas farraige go Loch Komani, aistri\u00fa b\u00e1id \u00f3 Koman go Fierze, turas b\u00e1id ar Abhainn Shala, n\u00f3 pac\u00e1iste taistil ioml\u00e1n Shkoder-Valbone le h\u00e1irithint amh\u00e1in.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-21d81e9 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"21d81e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Eisp\u00e9iris Bh\u00e1d Pr\u00e9imhe Loch Komani<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c8348d6 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"c8348d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>T\u00e9ann \u00e1r mbeala\u00ed tr\u00ed na canyons suntasacha, na f\u00e1na\u00ed g\u00e9ara sl\u00e9ibhe, agus uisc\u00ed emerald Loch Komani \u2014 a dh\u00e9antar compar\u00e1id idir iad agus fjords Lochlannacha go minic mar gheall ar a n-\u00e1illeacht n\u00e1d\u00fartha. <br>T\u00e1 gach turas deartha le bheith n\u00edos m\u00f3 n\u00e1 iompar; is turas farraige radharcach \u00e9 a thairgeann radhairc l\u00e1nl\u00e9argais, deiseanna grianghrafad\u00f3ireachta, agus nasc socair le n\u00e1d\u00far fi\u00e1in na hAlb\u00e1ine. <br>Cib\u00e9 acu aistri\u00fa b\u00e1id \u00f3 Koman go Fierze, turas farraige ar abhainn Koman go Shala, n\u00f3 turas lae ioml\u00e1in \u00f3 Shkoder go Valbone a roghna\u00edonn t\u00fa, d\u00e9antar gach bealach a phlean\u00e1il go c\u00faramach chun taisteal r\u00e9idh, imeachta\u00ed ponc\u00fala, agus compord paisin\u00e9ir\u00ed a chinnti\u00fa.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d3ec72a elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"d3ec72a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">B\u00e1d do Phaisin\u00e9ir\u00ed Amh\u00e1in &amp; Foireann Ghairmi\u00fail<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c54ca4f elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"c54ca4f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Is soitheach paisin\u00e9ir\u00ed amh\u00e1in \u00e9 Nord West Ferry a bhfuil toilleadh de thart ar 100 paisin\u00e9ir aige, at\u00e1 tiomnaithe go heisiach don bhealach seo \u2014 gan aon lasta n\u00e1 aon uala\u00ed troma.<br\/>T\u00e1 an b\u00e1d deartha le haghaidh cobhsa\u00edochta, sp\u00e1is agus compord ar Loch Komani agus d\u00e9antar \u00e9 a chothabh\u00e1il de r\u00e9ir caighde\u00e1n teicni\u00fail agus s\u00e1bh\u00e1ilteachta dochta.<br\/>Ar mhaithe le do sh\u00e1bh\u00e1ilteacht agus do shuaimhneas intinne:<br\/>\u2022 Seaic\u00e9id tarrth\u00e1la ar f\u00e1il do gach paisin\u00e9ir<br\/>\u2022 Captaein agus cri\u00fa cead\u00fanaithe agus taith\u00ed acu<br\/>\u2022 Cigireachta\u00ed teicni\u00fala agus seice\u00e1lacha s\u00e1bh\u00e1ilteachta rialta<br\/>\u2022 Eolas s\u00e1bh\u00e1ilteachta soil\u00e9ire roimh gach imeacht<br\/>N\u00ed rogha \u00ed an ts\u00e1bh\u00e1ilteacht \u2014 is \u00ed \u00e1r dtosa\u00edocht is airde \u00ed.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7fbc808 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"7fbc808\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Beala\u00ed Ioml\u00e1na &amp; R\u00e9itigh Taistil Aon-Thic\u00e9ad<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ccd6ad elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"7ccd6ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Speisialt\u00f3ireacht againn in aistrithe b\u00e1id aontreo agus i bpac\u00e1ist\u00ed taistil ioml\u00e1na araon, rud a fh\u00e1gann go bhfuil s\u00e9 \u00e9asca tuaisceart na hAlb\u00e1ine a ini\u00fachadh le cl\u00e1r taistil amh\u00e1in, dea-eagraithe.<br\/>\u00c1ir\u00edtear ar \u00e1r seirbh\u00eds\u00ed:<br\/>\u2022 Shkoder \u2013 Koman \u2013 Fierze \u2013 Valbone<br\/>\u2022 Shkoder \u2013 Koman \u2013 Abhainn Shala \u2013 Shkoder<br\/>\u2022 Valbone \u2013 Fierze \u2013 Koman \u2013 Shkoder<br\/>\u2022 Koman \u2013 Fierze (aontreo &#038; fillte)<br\/>\u2022 Koman \u2013 Abhainn Shala (aontreo &#038; fillte)<br\/>Tr\u00ed iompar b\u00f3thair agus turais bh\u00e1id a chomhcheangal, baintear strus na n-\u00e1irithint\u00ed iolracha agus cinnt\u00edmid eisp\u00e9ireas taistil r\u00e9idh.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-89ed098 e-flex e-con-boxed e-con e-parent\" data-id=\"89ed098\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c3ec0e0 elementor-widget-divider--view-line_text elementor-widget-divider--element-align-center elementor-invisible elementor-widget elementor-widget-divider\" data-id=\"c3ec0e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<span class=\"elementor-divider__text elementor-divider__element\">\n\t\t\t\tCad a dh\u00e9anaimid\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-db6eb51 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"db6eb51\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Ag Cruth\u00fa Do Eachtra Foirfe<br \/>i dTuaisceart na hAlb\u00e1ine<\/h1>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5b9e6a6 e-flex e-con-boxed e-con e-parent\" data-id=\"5b9e6a6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-25551c4 e-con-full e-flex e-con e-child\" data-id=\"25551c4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-427cfe5 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"427cfe5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;zoomIn&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5f017a7 elementor-view-stacked elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"5f017a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-sliders-h\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M496 384H160v-16c0-8.8-7.2-16-16-16h-32c-8.8 0-16 7.2-16 16v16H16c-8.8 0-16 7.2-16 16v32c0 8.8 7.2 16 16 16h80v16c0 8.8 7.2 16 16 16h32c8.8 0 16-7.2 16-16v-16h336c8.8 0 16-7.2 16-16v-32c0-8.8-7.2-16-16-16zm0-160h-80v-16c0-8.8-7.2-16-16-16h-32c-8.8 0-16 7.2-16 16v16H16c-8.8 0-16 7.2-16 16v32c0 8.8 7.2 16 16 16h336v16c0 8.8 7.2 16 16 16h32c8.8 0 16-7.2 16-16v-16h80c8.8 0 16-7.2 16-16v-32c0-8.8-7.2-16-16-16zm0-160H288V48c0-8.8-7.2-16-16-16h-32c-8.8 0-16 7.2-16 16v16H16C7.2 64 0 71.2 0 80v32c0 8.8 7.2 16 16 16h208v16c0 8.8 7.2 16 16 16h32c8.8 0 16-7.2 16-16v-16h208c8.8 0 16-7.2 16-16V80c0-8.8-7.2-16-16-16z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tSceideal Iontaofa &amp; Oibr\u00edochta\u00ed S\u00e9as\u00faracha \t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tOibr\u00edonn Nord West Ferry ar sceideal soil\u00e9ir agus iontaofa le linn an phr\u00edomhsh\u00e9as\u00fair taistil:<br \/>\u2022 Tr\u00e9imhse oibri\u00fach\u00e1in: 1 Bealtaine \u2013 1 Samhain\n\u2022 Imeacht \u00f3 Koman: 09:30\n\u2022 Imeacht \u00f3 Fierze: 12:30<br \/>T\u00e1 na sceideal go l\u00e9ir comhordaithe chun nascadh go r\u00e9idh le hiompar go Valbone agus Shkoder, rud a fh\u00e1gann go bhfuil s\u00e9 \u00e9asca plean\u00e1il a dh\u00e9anamh do thaistealaithe neamhsple\u00e1cha agus do ghr\u00fapa\u00ed eagraithe.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3fd6444 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"3fd6444\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;zoomIn&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b00db7a elementor-view-stacked elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"b00db7a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-map-marked-alt\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288 0c-69.59 0-126 56.41-126 126 0 56.26 82.35 158.8 113.9 196.02 6.39 7.54 17.82 7.54 24.2 0C331.65 284.8 414 182.26 414 126 414 56.41 357.59 0 288 0zm0 168c-23.2 0-42-18.8-42-42s18.8-42 42-42 42 18.8 42 42-18.8 42-42 42zM20.12 215.95A32.006 32.006 0 0 0 0 245.66v250.32c0 11.32 11.43 19.06 21.94 14.86L160 448V214.92c-8.84-15.98-16.07-31.54-21.25-46.42L20.12 215.95zM288 359.67c-14.07 0-27.38-6.18-36.51-16.96-19.66-23.2-40.57-49.62-59.49-76.72v182l192 64V266c-18.92 27.09-39.82 53.52-59.49 76.72-9.13 10.77-22.44 16.95-36.51 16.95zm266.06-198.51L416 224v288l139.88-55.95A31.996 31.996 0 0 0 576 426.34V176.02c0-11.32-11.43-19.06-21.94-14.86z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tDeartha do Thaistealaithe Idirn\u00e1isi\u00fanta\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tT\u00e1 \u00e1r seirbh\u00eds\u00ed deartha chun freastal ar chaighde\u00e1in taistil idirn\u00e1isi\u00fanta:<br \/>\u2022 Tic\u00e9id leictreonacha at\u00e1 furasta a \u00fas\u00e1id ar fh\u00f3in ph\u00f3ca\n\u2022 Deimhni\u00fa \u00e1irithinte tapa ar l\u00edne\n\u2022 Point\u00ed cruinnithe agus treoracha soil\u00e9ire<br \/>\u2022 C\u00fanamh ilteangach nuair is g\u00e1<br \/>\u2022 Taca\u00edocht ghairmi\u00fail do chustaim\u00e9ir\u00ed roimh agus le linn an turais<br \/>T\u00e1 \u00e1r dturais oiri\u00fanach do thaistealaithe aonair, do l\u00e1n\u00faineacha, do theaghlaigh, agus do lucht eachtra\u00edochta.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dfbb3ca e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"dfbb3ca\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;zoomIn&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d15e517 elementor-view-stacked elementor-shape-circle elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"d15e517\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-life-ring\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm173.696 119.559l-63.399 63.399c-10.987-18.559-26.67-34.252-45.255-45.255l63.399-63.399a218.396 218.396 0 0 1 45.255 45.255zM256 352c-53.019 0-96-42.981-96-96s42.981-96 96-96 96 42.981 96 96-42.981 96-96 96zM127.559 82.304l63.399 63.399c-18.559 10.987-34.252 26.67-45.255 45.255l-63.399-63.399a218.372 218.372 0 0 1 45.255-45.255zM82.304 384.441l63.399-63.399c10.987 18.559 26.67 34.252 45.255 45.255l-63.399 63.399a218.396 218.396 0 0 1-45.255-45.255zm302.137 45.255l-63.399-63.399c18.559-10.987 34.252-26.67 45.255-45.255l63.399 63.399a218.403 218.403 0 0 1-45.255 45.255z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tC\u00e9n F\u00e1th a Roghn\u00f3f\u00e1 Nord West Ferry\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t\u2714 Oibreoir turas cead\u00fanaithe agus gairmi\u00fail<br \/><br \/>\u2714 C\u00fars\u00e1il paisin\u00e9ir\u00ed amh\u00e1in ar Loch Komani<br \/><br \/>\u2714 Soith\u00ed s\u00e1bh\u00e1ilte le trealamh s\u00e1bh\u00e1ilteachta ioml\u00e1n<br \/><br \/>\u2714 Cri\u00fa \u00e1iti\u00fail a bhfuil taith\u00ed acu<br \/><br \/>\u2714 Taisteal gan uaim idir Shkoder, Koman, Fierze, agus Valbone<br \/><br \/>\u2714 Seirbh\u00eds iontaofa agus s\u00e1stacht ard custaim\u00e9ir\u00ed\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ca2b376 e-con-full e-flex e-con e-parent\" data-id=\"ca2b376\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-3cbcaea e-con-full e-flex e-con e-child\" data-id=\"3cbcaea\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6b61fd0 elementor-widget__width-inherit elementor-widget elementor-widget-image\" data-id=\"6b61fd0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1920\" height=\"1493\" src=\"https:\/\/komanlakeferry.com\/wp-content\/uploads\/2026\/01\/Koman-Lake-to-Shala-River-Scenic-Cruise.webp\" class=\"attachment-full size-full wp-image-5845\" alt=\"Boat cruise from Koman Lake to Shala River with mountain views\" srcset=\"https:\/\/komanlakeferry.com\/wp-content\/uploads\/2026\/01\/Koman-Lake-to-Shala-River-Scenic-Cruise.webp 1920w, https:\/\/komanlakeferry.com\/wp-content\/uploads\/2026\/01\/Koman-Lake-to-Shala-River-Scenic-Cruise-300x233.webp 300w, https:\/\/komanlakeferry.com\/wp-content\/uploads\/2026\/01\/Koman-Lake-to-Shala-River-Scenic-Cruise-1024x796.webp 1024w, https:\/\/komanlakeferry.com\/wp-content\/uploads\/2026\/01\/Koman-Lake-to-Shala-River-Scenic-Cruise-768x597.webp 768w, https:\/\/komanlakeferry.com\/wp-content\/uploads\/2026\/01\/Koman-Lake-to-Shala-River-Scenic-Cruise-1536x1194.webp 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3c2a779 e-con-full e-flex e-con e-child\" data-id=\"3c2a779\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-35a48d1 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"35a48d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Faigh amach Cro\u00edl\u00e1r<br \/>Thuaisceart na hAlb\u00e1ine<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-caf1a3c elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"caf1a3c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Ag Nord West Ferry, creidimid gur cheart go mbeadh n\u00edos m\u00f3 i gceist le taisteal n\u00e1 bogadh \u00f3 \u00e1it amh\u00e1in go h\u00e1it eile. <br>Is \u00e9 \u00e1r sprioc eisp\u00e9ireas bar\u00e1nt\u00fail, compordach agus cuimhneach\u00e1in a thairiscint a l\u00e9ir\u00edonn \u00e1illeacht Loch Komani, suaimhneas Abhainn Shala, agus eachtra\u00edocht bheala\u00ed sl\u00e9ibhe thuaisceart na hAlb\u00e1ine. <br>B\u00ed linn ar cheann de na turais b\u00e1id is radharcra san Eoraip \u2014 \u00e1 oibri\u00fa go gairmi\u00fail, eagraithe go s\u00e1bh\u00e1ilte, agus deartha do thaistealaithe a bhfuil meas acu ar ch\u00e1il\u00edocht.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5493fd8 e-con-full elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-parent\" data-id=\"5493fd8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1896302 elementor-widget-divider--view-line_text black-divider elementor-widget-divider--element-align-center elementor-invisible elementor-widget elementor-widget-divider\" data-id=\"1896302\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<span class=\"elementor-divider__text elementor-divider__element\">\n\t\t\t\tCluiche Ar Aghaidh Ceann Scr\u00edbe Eachtra\u00edochta\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4664704 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"4664704\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Faigh amach Cro\u00edl\u00e1r<br \/>Thuaisceart na hAlb\u00e1ine<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-333529a elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"333529a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Ag Nord West Cruise, creidimid gur cheart go mbeadh n\u00edos m\u00f3 i gceist le taisteal n\u00e1 bogadh \u00f3 \u00e1it amh\u00e1in go h\u00e1it eile. <br>Is \u00e9 \u00e1r sprioc eisp\u00e9ireas bar\u00e1nt\u00fail, compordach agus cuimhneach\u00e1in a thairiscint a l\u00e9ir\u00edonn \u00e1illeacht Loch Komani, suaimhneas Abhainn Shala, agus eachtra\u00edocht bheala\u00ed sl\u00e9ibhe thuaisceart na hAlb\u00e1ine. <br>B\u00ed linn ar cheann de na turais b\u00e1id is radharcra san Eoraip \u2014 \u00e1 oibri\u00fa go gairmi\u00fail, eagraithe go s\u00e1bh\u00e1ilte, agus deartha do thaistealaithe a bhfuil meas acu ar ch\u00e1il\u00edocht.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f5fdf9a elementor-invisible elementor-widget elementor-widget-button\" data-id=\"f5fdf9a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/komanlakeferry.com\/ga\/ar-turais\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-circle-right\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8c137 0 248 111 248 248S393 504 256 504 8 393 8 256 119 8 256 8zm-28.9 143.6l75.5 72.4H120c-13.3 0-24 10.7-24 24v16c0 13.3 10.7 24 24 24h182.6l-75.5 72.4c-9.7 9.3-9.9 24.8-.4 34.3l11 10.9c9.4 9.4 24.6 9.4 33.9 0L404.3 273c9.4-9.4 9.4-24.6 0-33.9L271.6 106.3c-9.4-9.4-24.6-9.4-33.9 0l-11 10.9c-9.5 9.6-9.3 25.1.4 34.4z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Turas Leabhar<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42d2a1a elementor-widget elementor-widget-heading\" data-id=\"42d2a1a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">INI\u00daCHADH AN ALB\u00c1IN<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f09fd25 e-flex e-con-boxed e-con e-parent\" data-id=\"f09fd25\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-93bb996 elementor-widget elementor-widget-html\" data-id=\"93bb996\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t\t<script>document.addEventListener(\"DOMContentLoaded\", function () {\r\n\r\n  const map = [\r\n    { section: \"#sec1\", dot: \"#dot1\" },\r\n    { section: \"#sec2\", dot: \"#dot2\" },\r\n    { section: \"#sec3\", dot: \"#dot3\" }\r\n  ];\r\n\r\n  const observer = new IntersectionObserver(\r\n    (entries) => {\r\n      entries.forEach(entry => {\r\n        if (entry.isIntersecting) {\r\n\r\n          \/\/ remove active from all dots\r\n          map.forEach(item => {\r\n            document.querySelector(item.dot)\r\n              .classList.remove(\"timeline-active\");\r\n          });\r\n\r\n          \/\/ activate the matching dot\r\n          const active = map.find(item => item.section === \"#\" + entry.target.id);\r\n          if (active) {\r\n            document.querySelector(active.dot)\r\n              .classList.add(\"timeline-active\");\r\n          }\r\n        }\r\n      });\r\n    },\r\n    {\r\n      threshold: 0.6\r\n    }\r\n  );\r\n\r\n  map.forEach(item => {\r\n    const section = document.querySelector(item.section);\r\n    if (section) observer.observe(section);\r\n  });\r\n\r\n});\r\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>About us NORDWEST Taisc\u00e9al Tuaisceart na hAlb\u00e1inele NordWest Is oibreoir turas gairmi\u00fail agus l\u00e1nchead\u00fanaithe \u00e9 Nord West Ferry at\u00e1 speisialaithe i dturais bh\u00e1id paisin\u00e9ir\u00ed pr\u00e9imhe agus i dtaith\u00ed taistil chomhcheangailte trasna Loch Komani \u2014 ceann de na cinn scr\u00edbe is radharcach agus is gan mhilleadh san Alb\u00e1in agus i r\u00e9igi\u00fan na mBalc\u00e1n. Is \u00e9 \u00e1r [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-5881","page","type-page","status-publish","hentry"],"acf":[],"_hostinger_reach_plugin_has_subscription_block":false,"_hostinger_reach_plugin_is_elementor":false,"_links":{"self":[{"href":"https:\/\/komanlakeferry.com\/ga\/wp-json\/wp\/v2\/pages\/5881","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/komanlakeferry.com\/ga\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/komanlakeferry.com\/ga\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/komanlakeferry.com\/ga\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/komanlakeferry.com\/ga\/wp-json\/wp\/v2\/comments?post=5881"}],"version-history":[{"count":2,"href":"https:\/\/komanlakeferry.com\/ga\/wp-json\/wp\/v2\/pages\/5881\/revisions"}],"predecessor-version":[{"id":6099,"href":"https:\/\/komanlakeferry.com\/ga\/wp-json\/wp\/v2\/pages\/5881\/revisions\/6099"}],"wp:attachment":[{"href":"https:\/\/komanlakeferry.com\/ga\/wp-json\/wp\/v2\/media?parent=5881"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}